{"id":309,"date":"2026-06-25T16:48:30","date_gmt":"2026-06-25T16:48:30","guid":{"rendered":"https:\/\/menfiservizi.it\/?p=309"},"modified":"2026-06-25T17:02:03","modified_gmt":"2026-06-25T17:02:03","slug":"avviate-le-procedure-di-selezione-personale-a-tempo-determinato-2","status":"publish","type":"post","link":"https:\/\/menfiservizi.it\/index.php\/2026\/06\/25\/avviate-le-procedure-di-selezione-personale-a-tempo-determinato-2\/","title":{"rendered":"Avviate le procedure di selezione personale a tempo determinato"},"content":{"rendered":"<div class=\"flex_column av_one_full  flex_column_div av-zero-column-padding first  avia-builder-el-0  el_before_av_textblock  avia-builder-el-first  \" style='border-radius:0px; '><section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock  '   itemprop=\"text\" ><h2 style=\"text-align: center;\">Avviate le procedure di selezione personale a tempo determinato<\/h2>\n<\/div><\/section><br \/>\n<div  class='avia-image-container  av-styling-    avia-builder-el-2  el_after_av_textblock  avia-builder-el-last  avia-align-center '  itemprop=\"image\" itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/ImageObject\"  ><div class='avia-image-container-inner'><div class='avia-image-overlay-wrap'><img decoding=\"async\" class='wp-image-220 avia-img-lazy-loading-not-220 avia_image' src=\"https:\/\/menfiservizi.it\/wp-content\/uploads\/2023\/02\/wintime_logo-80x80.png\" alt='' title='wintime_logo' height=\"80\" width=\"80\"  itemprop=\"thumbnailUrl\" srcset=\"https:\/\/menfiservizi.it\/wp-content\/uploads\/2023\/02\/wintime_logo-80x80.png 80w, https:\/\/menfiservizi.it\/wp-content\/uploads\/2023\/02\/wintime_logo-36x36.png 36w, https:\/\/menfiservizi.it\/wp-content\/uploads\/2023\/02\/wintime_logo-180x180.png 180w\" sizes=\"(max-width: 80px) 100vw, 80px\" \/><\/div><\/div><\/div><\/p><\/div>\n<section class=\"av_textblock_section \"  itemscope=\"itemscope\" itemtype=\"https:\/\/schema.org\/BlogPosting\" itemprop=\"blogPost\" ><div class='avia_textblock  '   itemprop=\"text\" ><p>La Menfi Servizi srl ha avviato, mediante societ\u00e0 di lavoro interinale, una selezione per l\u2019assunzione a tempo determinato di diverse unit\u00e0 lavorative di cui autista, operatori ecologici ed amministrativo. E\u2019 possibile avanzare le candidature, sul portale della Win Time spa (https:\/\/careers.wintimelavoro.com\/jobs.php) selezionando la regione Sicilia e la provincia di Agrigento.<\/p>\n<\/div><\/section>\n<div  class='avia-button-wrap avia-button-center  avia-builder-el-4  el_after_av_textblock  avia-builder-el-last ' ><a href='https:\/\/careers.wintimelavoro.com\/jobs.php'  class='avia-button  avia-color-theme-color   avia-icon_select-no avia-size-small avia-position-center '   ><span class='avia_iconbox_title' >ACCEDI AL SITO<\/span><\/a><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":220,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,4],"tags":[],"class_list":["post-309","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-gare-e","category-news"],"_links":{"self":[{"href":"https:\/\/menfiservizi.it\/index.php\/wp-json\/wp\/v2\/posts\/309","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/menfiservizi.it\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/menfiservizi.it\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/menfiservizi.it\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/menfiservizi.it\/index.php\/wp-json\/wp\/v2\/comments?post=309"}],"version-history":[{"count":2,"href":"https:\/\/menfiservizi.it\/index.php\/wp-json\/wp\/v2\/posts\/309\/revisions"}],"predecessor-version":[{"id":311,"href":"https:\/\/menfiservizi.it\/index.php\/wp-json\/wp\/v2\/posts\/309\/revisions\/311"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/menfiservizi.it\/index.php\/wp-json\/wp\/v2\/media\/220"}],"wp:attachment":[{"href":"https:\/\/menfiservizi.it\/index.php\/wp-json\/wp\/v2\/media?parent=309"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/menfiservizi.it\/index.php\/wp-json\/wp\/v2\/categories?post=309"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/menfiservizi.it\/index.php\/wp-json\/wp\/v2\/tags?post=309"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}